{"id":31439,"date":"2026-01-06T18:58:22","date_gmt":"2026-01-06T13:28:22","guid":{"rendered":"https:\/\/cdri.world\/?p=31439"},"modified":"2026-01-06T18:58:24","modified_gmt":"2026-01-06T13:28:24","slug":"only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed","status":"publish","type":"post","link":"https:\/\/cdri.world\/es\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/","title":{"rendered":"S\u00f3lo un tercio de las PYME del mundo est\u00e1n preparadas para las cat\u00e1strofes; las empresas indias, entre las m\u00e1s expuestas"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":31441,"comment_status":"open","ping_status":"open","sticky":false,"template":"post-with-no-url","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,955],"tags":[],"class_list":["post-31439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press","category-press-homepage"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Only a third of global SMEs are disaster-ready; Indian firms among most exposed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cdri.world\/es\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Only a third of global SMEs are disaster-ready; Indian firms among most exposed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cdri.world\/es\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T13:28:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T13:28:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"576\" \/>\n\t<meta property=\"og:image:height\" content=\"874\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aditya Patwa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aditya Patwa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/\"},\"author\":{\"name\":\"Aditya Patwa\",\"@id\":\"https:\/\/cdri.world\/#\/schema\/person\/fc8b0c8fbc88ef7b9f8f5152c08ebb9a\"},\"headline\":\"Only a third of global SMEs are disaster-ready; Indian firms among most exposed\",\"datePublished\":\"2026-01-06T13:28:22+00:00\",\"dateModified\":\"2026-01-06T13:28:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/\"},\"wordCount\":13,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdri.world\/#organization\"},\"image\":{\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg\",\"articleSection\":[\"Press\",\"press-homepage\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/\",\"url\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/\",\"name\":\"Only a third of global SMEs are disaster-ready; Indian firms among most exposed\",\"isPartOf\":{\"@id\":\"https:\/\/cdri.world\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg\",\"datePublished\":\"2026-01-06T13:28:22+00:00\",\"dateModified\":\"2026-01-06T13:28:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#primaryimage\",\"url\":\"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg\",\"contentUrl\":\"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg\",\"width\":576,\"height\":874,\"caption\":\"Only a third of global SMEs are disaster-ready; Indian firms among most exposed\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cdri.world\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Only a third of global SMEs are disaster-ready; Indian firms among most exposed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdri.world\/#website\",\"url\":\"https:\/\/cdri.world\/\",\"name\":\"CDRI\",\"description\":\"CDRI\",\"publisher\":{\"@id\":\"https:\/\/cdri.world\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdri.world\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdri.world\/#organization\",\"name\":\"Coalition for Disaster Resilient Infrastructure\",\"url\":\"https:\/\/cdri.world\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cdri.world\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2025\/09\/25100323\/cropped-CDRI-Logo-Black-and-Red.png\",\"contentUrl\":\"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2025\/09\/25100323\/cropped-CDRI-Logo-Black-and-Red.png\",\"width\":256,\"height\":70,\"caption\":\"Coalition for Disaster Resilient Infrastructure\"},\"image\":{\"@id\":\"https:\/\/cdri.world\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdri.world\/#\/schema\/person\/fc8b0c8fbc88ef7b9f8f5152c08ebb9a\",\"name\":\"Aditya Patwa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cdri.world\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/35601911e2428d08fed094635bfc086aa6255a0906ec04bf08151a4332f596c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/35601911e2428d08fed094635bfc086aa6255a0906ec04bf08151a4332f596c5?s=96&d=mm&r=g\",\"caption\":\"Aditya Patwa\"},\"url\":\"https:\/\/cdri.world\/es\/author\/paditya\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Only a third of global SMEs are disaster-ready; Indian firms among most exposed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cdri.world\/es\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/","og_locale":"es_ES","og_type":"article","og_title":"Only a third of global SMEs are disaster-ready; Indian firms among most exposed","og_url":"https:\/\/cdri.world\/es\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/","article_published_time":"2026-01-06T13:28:22+00:00","article_modified_time":"2026-01-06T13:28:24+00:00","og_image":[{"width":576,"height":874,"url":"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg","type":"image\/jpeg"}],"author":"Aditya Patwa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aditya Patwa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#article","isPartOf":{"@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/"},"author":{"name":"Aditya Patwa","@id":"https:\/\/cdri.world\/#\/schema\/person\/fc8b0c8fbc88ef7b9f8f5152c08ebb9a"},"headline":"Only a third of global SMEs are disaster-ready; Indian firms among most exposed","datePublished":"2026-01-06T13:28:22+00:00","dateModified":"2026-01-06T13:28:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/"},"wordCount":13,"commentCount":0,"publisher":{"@id":"https:\/\/cdri.world\/#organization"},"image":{"@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#primaryimage"},"thumbnailUrl":"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg","articleSection":["Press","press-homepage"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/","url":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/","name":"Only a third of global SMEs are disaster-ready; Indian firms among most exposed","isPartOf":{"@id":"https:\/\/cdri.world\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#primaryimage"},"image":{"@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#primaryimage"},"thumbnailUrl":"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg","datePublished":"2026-01-06T13:28:22+00:00","dateModified":"2026-01-06T13:28:24+00:00","breadcrumb":{"@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#primaryimage","url":"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg","contentUrl":"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2026\/01\/06185806\/TM-Aaron-Schubert-1.jpg","width":576,"height":874,"caption":"Only a third of global SMEs are disaster-ready; Indian firms among most exposed"},{"@type":"BreadcrumbList","@id":"https:\/\/cdri.world\/only-a-third-of-global-smes-are-disaster-ready-indian-firms-among-most-exposed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cdri.world\/"},{"@type":"ListItem","position":2,"name":"Only a third of global SMEs are disaster-ready; Indian firms among most exposed"}]},{"@type":"WebSite","@id":"https:\/\/cdri.world\/#website","url":"https:\/\/cdri.world\/","name":"CDRI","description":"CDRI","publisher":{"@id":"https:\/\/cdri.world\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdri.world\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cdri.world\/#organization","name":"Coalition for Disaster Resilient Infrastructure","url":"https:\/\/cdri.world\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cdri.world\/#\/schema\/logo\/image\/","url":"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2025\/09\/25100323\/cropped-CDRI-Logo-Black-and-Red.png","contentUrl":"https:\/\/dymez6ioe12by.cloudfront.net\/media\/wp-content\/uploads\/2025\/09\/25100323\/cropped-CDRI-Logo-Black-and-Red.png","width":256,"height":70,"caption":"Coalition for Disaster Resilient Infrastructure"},"image":{"@id":"https:\/\/cdri.world\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdri.world\/#\/schema\/person\/fc8b0c8fbc88ef7b9f8f5152c08ebb9a","name":"Aditya Patwa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cdri.world\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/35601911e2428d08fed094635bfc086aa6255a0906ec04bf08151a4332f596c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35601911e2428d08fed094635bfc086aa6255a0906ec04bf08151a4332f596c5?s=96&d=mm&r=g","caption":"Aditya Patwa"},"url":"https:\/\/cdri.world\/es\/author\/paditya\/"}]}},"_links":{"self":[{"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/posts\/31439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/comments?post=31439"}],"version-history":[{"count":1,"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/posts\/31439\/revisions"}],"predecessor-version":[{"id":31442,"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/posts\/31439\/revisions\/31442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/media\/31441"}],"wp:attachment":[{"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/media?parent=31439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/categories?post=31439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdri.world\/es\/wp-json\/wp\/v2\/tags?post=31439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}